{"id":2983,"date":"2025-05-12T10:49:49","date_gmt":"2025-05-12T08:49:49","guid":{"rendered":"https:\/\/www.inoxveneta.com\/fianchi-idroformati-fianco-per-armadio-refrigerato\/"},"modified":"2026-07-17T10:58:56","modified_gmt":"2026-07-17T08:58:56","slug":"hydroformed-sides-side-panel-for-refrigerated-cabinet","status":"publish","type":"post","link":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/","title":{"rendered":"Hydroformed Sides \u2013 Side Panel for Refrigerated Cabinet"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":2072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[49],"tags":[],"class_list":["post-2983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hydroformed Sides \u2013 Side Panel for Refrigerated Cabinet - Inoxveneta<\/title>\n<meta name=\"description\" content=\"Hydroformed stainless steel AISI 304 sides for refrigerated cabinets: aesthetics, flatness, and clean lines. Flexible, solid solutions for professional kitchens, trolleys, and dishwashers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hydroformed Sides \u2013 Side Panel for Refrigerated Cabinet - Inoxveneta\" \/>\n<meta property=\"og:description\" content=\"Hydroformed stainless steel AISI 304 sides for refrigerated cabinets: aesthetics, flatness, and clean lines. Flexible, solid solutions for professional kitchens, trolleys, and dishwashers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/\" \/>\n<meta property=\"og:site_name\" content=\"Inoxveneta\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-12T08:49:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-17T08:58:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inoxveneta.com\/wp-content\/uploads\/2025\/05\/1-Fianchi-e-Fondi-Slider-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"807\" \/>\n\t<meta property=\"og:image:height\" content=\"538\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"svetlana.skalega\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"svetlana.skalega\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"Article\",\n\t            \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/#article\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/\"\n\t            },\n\t            \"author\": {\n\t                \"name\": \"svetlana.skalega\",\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#\\\/schema\\\/person\\\/46eb3c6b183b985e58eb48a7696abd16\"\n\t            },\n\t            \"headline\": \"Hydroformed Sides \u2013 Side Panel for Refrigerated Cabinet\",\n\t            \"datePublished\": \"2025-05-12T08:49:49+00:00\",\n\t            \"dateModified\": \"2026-07-17T08:58:56+00:00\",\n\t            \"mainEntityOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/\"\n\t            },\n\t            \"wordCount\": 7,\n\t            \"publisher\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#organization\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/www.inoxveneta.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1-Fianchi-e-Fondi-Slider-2.png\",\n\t            \"articleSection\": [\n\t                \"News\"\n\t            ],\n\t            \"inLanguage\": \"en-US\"\n\t        },\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/\",\n\t            \"url\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/\",\n\t            \"name\": \"Hydroformed Sides \u2013 Side Panel for Refrigerated Cabinet - Inoxveneta\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/www.inoxveneta.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1-Fianchi-e-Fondi-Slider-2.png\",\n\t            \"datePublished\": \"2025-05-12T08:49:49+00:00\",\n\t            \"dateModified\": \"2026-07-17T08:58:56+00:00\",\n\t            \"description\": \"Hydroformed stainless steel AISI 304 sides for refrigerated cabinets: aesthetics, flatness, and clean lines. Flexible, solid solutions for professional kitchens, trolleys, and dishwashers.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"en-US\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"en-US\",\n\t            \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/www.inoxveneta.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1-Fianchi-e-Fondi-Slider-2.png\",\n\t            \"contentUrl\": \"https:\\\/\\\/www.inoxveneta.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1-Fianchi-e-Fondi-Slider-2.png\",\n\t            \"width\": 807,\n\t            \"height\": 538\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/hydroformed-sides-side-panel-for-refrigerated-cabinet\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Hydroformed Sides \u2013 Side Panel for Refrigerated Cabinet\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/\",\n\t            \"name\": \"Inoxveneta\",\n\t            \"description\": \"\",\n\t            \"publisher\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#organization\"\n\t            },\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"en-US\"\n\t        },\n\t        {\n\t            \"@type\": \"Organization\",\n\t            \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#organization\",\n\t            \"name\": \"Inoxveneta\",\n\t            \"alternateName\": \"Inoxveneta S.p.A.\",\n\t            \"url\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/\",\n\t            \"logo\": {\n\t                \"@type\": \"ImageObject\",\n\t                \"inLanguage\": \"en-US\",\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\n\t                \"url\": \"https:\\\/\\\/www.inoxveneta.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-inoxveneta.png\",\n\t                \"contentUrl\": \"https:\\\/\\\/www.inoxveneta.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-inoxveneta.png\",\n\t                \"width\": 282,\n\t                \"height\": 179,\n\t                \"caption\": \"Inoxveneta\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"\n\t            },\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/www.linkedin.com\\\/company\\\/68255102\",\n\t                \"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDmX6WB-Twk6NkRThygfsXA\",\n\t                \"https:\\\/\\\/www.wikidata.org\\\/wiki\\\/Q140387674\",\n\t                \"https:\\\/\\\/www.crunchbase.com\\\/organization\\\/inoxveneta\"\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"Person\",\n\t            \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#\\\/schema\\\/person\\\/46eb3c6b183b985e58eb48a7696abd16\",\n\t            \"name\": \"svetlana.skalega\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hydroformed Sides \u2013 Side Panel for Refrigerated Cabinet - Inoxveneta","description":"Hydroformed stainless steel AISI 304 sides for refrigerated cabinets: aesthetics, flatness, and clean lines. Flexible, solid solutions for professional kitchens, trolleys, and dishwashers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/","og_locale":"en_US","og_type":"article","og_title":"Hydroformed Sides \u2013 Side Panel for Refrigerated Cabinet - Inoxveneta","og_description":"Hydroformed stainless steel AISI 304 sides for refrigerated cabinets: aesthetics, flatness, and clean lines. Flexible, solid solutions for professional kitchens, trolleys, and dishwashers.","og_url":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/","og_site_name":"Inoxveneta","article_published_time":"2025-05-12T08:49:49+00:00","article_modified_time":"2026-07-17T08:58:56+00:00","og_image":[{"width":807,"height":538,"url":"https:\/\/www.inoxveneta.com\/wp-content\/uploads\/2025\/05\/1-Fianchi-e-Fondi-Slider-2.png","type":"image\/png"}],"author":"svetlana.skalega","twitter_card":"summary_large_image","twitter_misc":{"Written by":"svetlana.skalega","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/#article","isPartOf":{"@id":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/"},"author":{"name":"svetlana.skalega","@id":"https:\/\/www.inoxveneta.com\/en\/#\/schema\/person\/46eb3c6b183b985e58eb48a7696abd16"},"headline":"Hydroformed Sides \u2013 Side Panel for Refrigerated Cabinet","datePublished":"2025-05-12T08:49:49+00:00","dateModified":"2026-07-17T08:58:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/"},"wordCount":7,"publisher":{"@id":"https:\/\/www.inoxveneta.com\/en\/#organization"},"image":{"@id":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inoxveneta.com\/wp-content\/uploads\/2025\/05\/1-Fianchi-e-Fondi-Slider-2.png","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/","url":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/","name":"Hydroformed Sides \u2013 Side Panel for Refrigerated Cabinet - Inoxveneta","isPartOf":{"@id":"https:\/\/www.inoxveneta.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/#primaryimage"},"image":{"@id":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inoxveneta.com\/wp-content\/uploads\/2025\/05\/1-Fianchi-e-Fondi-Slider-2.png","datePublished":"2025-05-12T08:49:49+00:00","dateModified":"2026-07-17T08:58:56+00:00","description":"Hydroformed stainless steel AISI 304 sides for refrigerated cabinets: aesthetics, flatness, and clean lines. Flexible, solid solutions for professional kitchens, trolleys, and dishwashers.","breadcrumb":{"@id":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/#primaryimage","url":"https:\/\/www.inoxveneta.com\/wp-content\/uploads\/2025\/05\/1-Fianchi-e-Fondi-Slider-2.png","contentUrl":"https:\/\/www.inoxveneta.com\/wp-content\/uploads\/2025\/05\/1-Fianchi-e-Fondi-Slider-2.png","width":807,"height":538},{"@type":"BreadcrumbList","@id":"https:\/\/www.inoxveneta.com\/en\/hydroformed-sides-side-panel-for-refrigerated-cabinet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inoxveneta.com\/en\/"},{"@type":"ListItem","position":2,"name":"Hydroformed Sides \u2013 Side Panel for Refrigerated Cabinet"}]},{"@type":"WebSite","@id":"https:\/\/www.inoxveneta.com\/en\/#website","url":"https:\/\/www.inoxveneta.com\/en\/","name":"Inoxveneta","description":"","publisher":{"@id":"https:\/\/www.inoxveneta.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inoxveneta.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.inoxveneta.com\/en\/#organization","name":"Inoxveneta","alternateName":"Inoxveneta S.p.A.","url":"https:\/\/www.inoxveneta.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.inoxveneta.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.inoxveneta.com\/wp-content\/uploads\/2026\/03\/logo-inoxveneta.png","contentUrl":"https:\/\/www.inoxveneta.com\/wp-content\/uploads\/2026\/03\/logo-inoxveneta.png","width":282,"height":179,"caption":"Inoxveneta"},"image":{"@id":"https:\/\/www.inoxveneta.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/68255102","https:\/\/www.youtube.com\/channel\/UCDmX6WB-Twk6NkRThygfsXA","https:\/\/www.wikidata.org\/wiki\/Q140387674","https:\/\/www.crunchbase.com\/organization\/inoxveneta"]},{"@type":"Person","@id":"https:\/\/www.inoxveneta.com\/en\/#\/schema\/person\/46eb3c6b183b985e58eb48a7696abd16","name":"svetlana.skalega"}]}},"_links":{"self":[{"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/posts\/2983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/comments?post=2983"}],"version-history":[{"count":1,"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/posts\/2983\/revisions"}],"predecessor-version":[{"id":6091,"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/posts\/2983\/revisions\/6091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/media\/2072"}],"wp:attachment":[{"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/media?parent=2983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/categories?post=2983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/tags?post=2983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}