{"id":2895,"date":"2024-06-10T14:36:18","date_gmt":"2024-06-10T12:36:18","guid":{"rendered":"https:\/\/www.inoxveneta.com\/contattaci\/"},"modified":"2026-05-15T10:04:57","modified_gmt":"2026-05-15T08:04:57","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/www.inoxveneta.com\/en\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/tpl-contacts.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2895","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact Us - Inoxveneta<\/title>\n<meta name=\"description\" content=\"Contact Inoxveneta for custom stainless steel solutions: hydroforming, electrical panels, and kitchen components. Expert support, production efficiency, and innovative design.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inoxveneta.com\/en\/contact-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Us - Inoxveneta\" \/>\n<meta property=\"og:description\" content=\"Contact Inoxveneta for custom stainless steel solutions: hydroforming, electrical panels, and kitchen components. Expert support, production efficiency, and innovative design.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inoxveneta.com\/en\/contact-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Inoxveneta\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-15T08:04:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/contact-us\\\/\",\n\t            \"url\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/contact-us\\\/\",\n\t            \"name\": \"Contact Us - Inoxveneta\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2024-06-10T12:36:18+00:00\",\n\t            \"dateModified\": \"2026-05-15T08:04:57+00:00\",\n\t            \"description\": \"Contact Inoxveneta for custom stainless steel solutions: hydroforming, electrical panels, and kitchen components. Expert support, production efficiency, and innovative design.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/contact-us\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"en-US\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/contact-us\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/contact-us\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Contact Us\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/\",\n\t            \"name\": \"Inoxveneta\",\n\t            \"description\": \"\",\n\t            \"publisher\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#organization\"\n\t            },\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"en-US\"\n\t        },\n\t        {\n\t            \"@type\": \"Organization\",\n\t            \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#organization\",\n\t            \"name\": \"Inoxveneta\",\n\t            \"alternateName\": \"Inoxveneta S.p.A.\",\n\t            \"url\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/\",\n\t            \"logo\": {\n\t                \"@type\": \"ImageObject\",\n\t                \"inLanguage\": \"en-US\",\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\n\t                \"url\": \"https:\\\/\\\/www.inoxveneta.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-inoxveneta.png\",\n\t                \"contentUrl\": \"https:\\\/\\\/www.inoxveneta.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/logo-inoxveneta.png\",\n\t                \"width\": 282,\n\t                \"height\": 179,\n\t                \"caption\": \"Inoxveneta\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/www.inoxveneta.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"\n\t            },\n\t            \"sameAs\": [\n\t                \"https:\\\/\\\/www.linkedin.com\\\/company\\\/68255102\",\n\t                \"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCDmX6WB-Twk6NkRThygfsXA\",\n\t                \"https:\\\/\\\/www.wikidata.org\\\/wiki\\\/Q140387674\",\n\t                \"https:\\\/\\\/www.crunchbase.com\\\/organization\\\/inoxveneta\"\n\t            ]\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact Us - Inoxveneta","description":"Contact Inoxveneta for custom stainless steel solutions: hydroforming, electrical panels, and kitchen components. Expert support, production efficiency, and innovative design.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inoxveneta.com\/en\/contact-us\/","og_locale":"en_US","og_type":"article","og_title":"Contact Us - Inoxveneta","og_description":"Contact Inoxveneta for custom stainless steel solutions: hydroforming, electrical panels, and kitchen components. Expert support, production efficiency, and innovative design.","og_url":"https:\/\/www.inoxveneta.com\/en\/contact-us\/","og_site_name":"Inoxveneta","article_modified_time":"2026-05-15T08:04:57+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.inoxveneta.com\/en\/contact-us\/","url":"https:\/\/www.inoxveneta.com\/en\/contact-us\/","name":"Contact Us - Inoxveneta","isPartOf":{"@id":"https:\/\/www.inoxveneta.com\/en\/#website"},"datePublished":"2024-06-10T12:36:18+00:00","dateModified":"2026-05-15T08:04:57+00:00","description":"Contact Inoxveneta for custom stainless steel solutions: hydroforming, electrical panels, and kitchen components. Expert support, production efficiency, and innovative design.","breadcrumb":{"@id":"https:\/\/www.inoxveneta.com\/en\/contact-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inoxveneta.com\/en\/contact-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.inoxveneta.com\/en\/contact-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inoxveneta.com\/en\/"},{"@type":"ListItem","position":2,"name":"Contact Us"}]},{"@type":"WebSite","@id":"https:\/\/www.inoxveneta.com\/en\/#website","url":"https:\/\/www.inoxveneta.com\/en\/","name":"Inoxveneta","description":"","publisher":{"@id":"https:\/\/www.inoxveneta.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inoxveneta.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.inoxveneta.com\/en\/#organization","name":"Inoxveneta","alternateName":"Inoxveneta S.p.A.","url":"https:\/\/www.inoxveneta.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.inoxveneta.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.inoxveneta.com\/wp-content\/uploads\/2026\/03\/logo-inoxveneta.png","contentUrl":"https:\/\/www.inoxveneta.com\/wp-content\/uploads\/2026\/03\/logo-inoxveneta.png","width":282,"height":179,"caption":"Inoxveneta"},"image":{"@id":"https:\/\/www.inoxveneta.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/68255102","https:\/\/www.youtube.com\/channel\/UCDmX6WB-Twk6NkRThygfsXA","https:\/\/www.wikidata.org\/wiki\/Q140387674","https:\/\/www.crunchbase.com\/organization\/inoxveneta"]}]}},"_links":{"self":[{"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/pages\/2895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/comments?post=2895"}],"version-history":[{"count":1,"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/pages\/2895\/revisions"}],"predecessor-version":[{"id":5952,"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/pages\/2895\/revisions\/5952"}],"wp:attachment":[{"href":"https:\/\/www.inoxveneta.com\/en\/wp-json\/wp\/v2\/media?parent=2895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}